{"id":3731,"date":"2021-06-11T17:38:40","date_gmt":"2021-06-11T15:38:40","guid":{"rendered":"https:\/\/www.panalabel.com\/etiquetas-a4\/"},"modified":"2021-07-14T17:45:08","modified_gmt":"2021-07-14T15:45:08","slug":"a4-labels","status":"publish","type":"page","link":"https:\/\/www.panalabel.com\/en\/a4-labels\/","title":{"rendered":"A4 Labels"},"content":{"rendered":"[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; layer_one_image=&#8221;2518&#8243; layer_four_image=&#8221;2655&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;light&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<style type=\"text\/css\">@media only screen and (min-width: 1300px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 480px; }  } @media only screen and (max-width: 1299px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 400px; }  } @media only screen and (max-width: 1000px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 342.85714285714px; }  } @media only screen and (max-width: 690px) { #nectar-slider-instance-1, #nectar-slider-instance-1 .swiper-container { height: 177.77777777778px; }  } <\/style><div data-midnight=\"nectar-slider\" class=\"parallax_slider_outer \"><div  data-transition=\"fade\" data-overall_style=\"classic\" data-flexible-height=\"\" data-animate-in-effect=\"none\" data-fullscreen=\"false\" data-button-sizing=\"regular\" data-button-styling=\"btn_with_count\" data-autorotate=\"5000\" data-parallax=\"true\" data-parallax-disable-mobile=\"\" data-caption-trans=\"fade_in_from_bottom\" data-parallax-style=\"bg_only\" data-bg-animation=\"none\" data-full-width=\"true\" class=\"nectar-slider-wrap \" id=\"nectar-slider-instance-1\"><div class=\"swiper-container\"  data-tho=\"auto\" data-tco=\"auto\" data-pho=\"auto\" data-pco=\"auto\" data-loop=\"false\" data-height=\"480\" data-min-height=\"\" data-arrows=\"false\" data-bullets=\"false\" data-bullet_style=\"see_through\" data-bullet_position=\"bottom\" data-desktop-swipe=\"false\" data-settings=\"\"> <div class=\"swiper-wrapper\"><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.panalabel.com\/wp-content\/uploads\/2021\/06\/panalabel-a4-labelsc.jpg);\"> &nbsp; <\/div><\/div><a href=\"#\" class=\"slider-down-arrow\"><i class=\"icon-salient-down-arrow icon-default-style\"> <span class=\"ie-fix\"><\/span> <\/i><\/a><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.panalabel.com\/wp-content\/uploads\/2021\/05\/panalabel-labelsa4-2.jpg);\"> &nbsp; <\/div><\/div><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.panalabel.com\/wp-content\/uploads\/2021\/06\/DSC05650.jpg);\"> &nbsp; <\/div><\/div><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"top\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.panalabel.com\/wp-content\/uploads\/2021\/05\/panalabel-labels-bobina2.jpg);\"> &nbsp; <\/div><\/div><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.panalabel.com\/wp-content\/uploads\/2021\/06\/barcode-panalabel-labels.jpg);\"> &nbsp; <\/div><\/div><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><div class=\"swiper-slide\" data-desktop-content-width=\"\" data-tablet-content-width=\"\" data-bg-alignment=\"center\" data-color-scheme=\"light\" data-x-pos=\"center\" data-y-pos=\"middle\" ><div class=\"slide-bg-wrap\"><div class=\"image-bg\" style=\"background-image: url(https:\/\/www.panalabel.com\/wp-content\/uploads\/2021\/05\/panalabel-etiquetas-f01.jpg);\"> &nbsp; <\/div><\/div><div class=\"video-texture \"> <span class=\"ie-fix\"><\/span> <\/div><\/div> <!--\/swiper-slide--><\/div><div class=\"nectar-slider-loading \"> <span class=\"loading-icon none\">   <\/span> <\/div> <\/div> \r\n\t\t\t\t\t\r\n\t\t\t\t\t<\/div><\/div>[\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#fbfbfb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#f5f5f5&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-th accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h4>A4 labels<\/h4>\n<p>We have a very extensive range of A4 and A5 labels, made with chlorine-free paper and acrylic adhesive to guarantee their correct operation in printers. They work on both laser printers, inkjet printers, and copiers. Our standardized presentations are in packages of 100 or 500 sheets. We can also make any type of A4 and A5 labels in other materials and other adhesives. <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60&#8243;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-caret-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>Standard<\/h2>\n <\/div><div class=\"clear\"><\/div><\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;40&#8243;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;3513,3508,3503,3498,3493,3488,3483,3458,3649,3473,3468,3463,3453,3448,3443,3428,3438,3433,3423,3413,3398,3655,3408,3403&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;4&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;1&#8243; load_in_animation=&#8221;none&#8221; el_id=&#8221;a4&#8243; img_size=&#8221;full&#8221;][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;60&#8243;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-caret-right accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h2>Round corners<\/h2>\n <\/div><div class=\"clear\"><\/div><\/div>[divider line_type=&#8221;No Line&#8221; custom_height=&#8221;40&#8243;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;3543,3538,3533,3548,3553,3528,3523,3518&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;4&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;1&#8243; load_in_animation=&#8221;none&#8221; img_size=&#8221;full&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;20px&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<div id=\"footable_parent_3744\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent semantic_ui \">\n                    <h3 class=\"table_title footable_title\">A4 Labels<\/h3>\n                        <table data-ninja_table_instance=\"ninja_table_instance_0\" data-footable_id=\"3744\" data-filter-delay=\"1000\" aria-label=\"A4 Labels\"            id=\"footable_3744\"\n           data-unique_identifier=\"ninja_table_unique_id_328549990_3744\"\n           class=\" foo-table ninja_footable foo_table_3744 ninja_table_unique_id_328549990_3744 ui table  nt_type_ajax_table selectable celled striped compact vertical_centered  footable-paging-right ninja_table_search_disabled\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n[\/vc_column_text][vc_column_text]<div id=\"footable_parent_3742\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent semantic_ui \">\n                    <h3 class=\"table_title footable_title\">A4 Labels Round corners<\/h3>\n                        <table data-ninja_table_instance=\"ninja_table_instance_1\" data-footable_id=\"3742\" data-filter-delay=\"1000\" aria-label=\"A4 Labels Round corners\"            id=\"footable_3742\"\n           data-unique_identifier=\"ninja_table_unique_id_215909114_3742\"\n           class=\" foo-table ninja_footable foo_table_3742 ninja_table_unique_id_215909114_3742 ui table  nt_type_ajax_table selectable celled striped compact vertical_centered  footable-paging-right ninja_table_search_disabled\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#fbfbfb&#8221; scene_position=&#8221;center&#8221; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-5-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#f5f5f5&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;2\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_row_inner column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; text_align=&#8221;left&#8221;][vc_column_inner column_padding=&#8221;padding-1-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;]<div class=\"iwithtext\"><div class=\"iwt-icon\"> <i class=\"icon-default-style fa fa-th accent-color\"><\/i> <\/div><div class=\"iwt-text\"> \n<h4>Etiquetas A4<\/h4>\n<p>Disponemos de una gama muy extensa de etiquetas A4 y A5, fabricadas con papel libre de cloro y adhesivo acr\u00edlico para garantizar su correcto funcionamiento en las impresoras.\u00a0 Funcionan tanto en impresoras laser, inyecci\u00f3n de tinta y fotocopiadoras. Nuestras presentaciones estandarizadas son en paquetes de 100 o 500 hojas. Tambi\u00e9n podemos hacer cualquier tipo de etiquetas A4 y A5 en otros materiales y otros adhesivos. <\/div><div class=\"clear\"><\/div><\/div>[\/vc_column_inner][\/vc_row_inner][divider line_type=&#8221;No Line&#8221; custom_height=&#8221;30&#8243;][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;3398,3403,3408,3413,3655,3423,3428,3433,3438,3443,3448,3453,3458,3463,3468,3473,3649,3483,3488,3493,3498,3503,3508,3513,3518,3523,3528,3533,3538,3548,3553,3543&#8243; image_grid_loading=&#8221;default&#8221; layout=&#8221;4&#8243; item_spacing=&#8221;default&#8221; gallery_style=&#8221;1&#8243; load_in_animation=&#8221;none&#8221; img_size=&#8221;full&#8221;][\/vc_column][vc_column column_padding=&#8221;padding-3-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;20px&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/3&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]<div id=\"footable_parent_3567\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent semantic_ui \">\n                    <h3 class=\"table_title footable_title\">Etiquetas A4 Standard<\/h3>\n                        <table data-ninja_table_instance=\"ninja_table_instance_2\" data-footable_id=\"3567\" data-filter-delay=\"1000\" aria-label=\"Etiquetas A4 Standard\"            id=\"footable_3567\"\n           data-unique_identifier=\"ninja_table_unique_id_1031279049_3567\"\n           class=\" foo-table ninja_footable foo_table_3567 ninja_table_unique_id_1031279049_3567 ui table  nt_type_ajax_table selectable celled striped compact vertical_centered  footable-paging-right ninja_table_search_disabled\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n[\/vc_column_text][vc_column_text]<div id=\"footable_parent_3571\"\n         class=\" footable_parent ninja_table_wrapper loading_ninja_table wp_table_data_press_parent semantic_ui \">\n                    <h3 class=\"table_title footable_title\">Etiquetas A4 Canto redondo<\/h3>\n                        <table data-ninja_table_instance=\"ninja_table_instance_3\" data-footable_id=\"3571\" data-filter-delay=\"1000\" aria-label=\"Etiquetas A4 Canto redondo\"            id=\"footable_3571\"\n           data-unique_identifier=\"ninja_table_unique_id_2027550305_3571\"\n           class=\" foo-table ninja_footable foo_table_3571 ninja_table_unique_id_2027550305_3571 ui table  nt_type_ajax_table selectable celled striped compact vertical_centered  footable-paging-right ninja_table_search_disabled\">\n                <colgroup>\n                            <col class=\"ninja_column_0 \">\n                            <col class=\"ninja_column_1 \">\n                            <col class=\"ninja_column_2 \">\n                            <col class=\"ninja_column_3 \">\n                    <\/colgroup>\n            <\/table>\n    \n    \n    \n<\/div>\n[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; bg_color=&#8221;#f9f9f9&#8243; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-7-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#f9f9f9&#8243; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3 class=\"tiny\">Seeing Is Believing<\/h3>\n[divider line_type=&#8221;Small Line&#8221; custom_height=&#8221;50&#8243;]\n<h2>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Maecenas ut mi ornare, pretium massa eu, rutrum enim. In in lorem congue, tincidunt justo at, consectetur nulla.<\/h2>\n<p><em><a href=\"#\">View The Goods<\/a><br \/>\n<\/em>[\/vc_column_text][\/vc_column][vc_column column_padding=&#8221;padding-7-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color=&#8221;#ffffff&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/2&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text]\n<h3 class=\"tiny\">We Blog Too<\/h3>\n[divider line_type=&#8221;Small Line&#8221; custom_height=&#8221;50&#8243;]\n<h2>Lorem ipsum dolor sit amet, consectetur adipiscing elit. Maecenas ut mi ornare, pretium massa eu, rutrum enim. In in lorem congue, tincidunt justo at, consectetur nulla.<\/h2>\n<p><em><a href=\"#\">Pick OurBrains<\/a><br \/>\n<\/em>[\/vc_column_text][\/vc_column][\/vc_row][vc_row type=&#8221;full_width_content&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;light&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221; shape_type=&#8221;&#8221;][vc_column column_padding=&#8221;padding-2-percent&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; centered_text=&#8221;true&#8221; background_color=&#8221;#f96566&#8243; background_color_opacity=&#8221;1&#8243; background_color_hover=&#8221;#ed6263&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221; gradient_direction=&#8221;left_to_right&#8221; overlay_strength=&#8221;0.3&#8243; width=&#8221;1\/1&#8243; tablet_width_inherit=&#8221;default&#8221; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; bg_image_animation=&#8221;none&#8221; border_type=&#8221;simple&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221; column_link=&#8221;#&#8221;][vc_column_text]Let&#8217;s take the next step and work together[\/vc_column_text][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;full_width_background&#8221; full_screen_row_position=&#8221;middle&#8221; column_margin=&#8221;default&#8221; column_direction=&#8221;default&#8221; column_direction_tablet=&#8221;default&#8221; column_direction_phone=&#8221;default&#8221; scene_position=&#8221;center&#8221; layer_one_image=&#8221;2518&#8243; layer_four_image=&#8221;2655&#8243; top_padding=&#8221;0&#8243; bottom_padding=&#8221;0&#8243; text_color=&#8221;light&#8221; text_align=&#8221;center&#8221; row_border_radius=&#8221;none&#8221; row_border_radius_applies=&#8221;bg&#8221; overlay_strength=&#8221;0.3&#8243; gradient_direction=&#8221;left_to_right&#8221; shape_divider_position=&#8221;bottom&#8221; bg_image_animation=&#8221;none&#8221;][vc_column column_padding=&#8221;no-extra-padding&#8221; column_padding_tablet=&#8221;inherit&#8221; column_padding_phone=&#8221;inherit&#8221; column_padding_position=&#8221;all&#8221; column_element_spacing=&#8221;default&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; column_border_radius=&#8221;none&#8221; column_link_target=&#8221;_self&#8221;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":34,"comment_status":"open","ping_status":"open","template":"","meta":[],"_links":{"self":[{"href":"https:\/\/www.panalabel.com\/en\/wp-json\/wp\/v2\/pages\/3731"}],"collection":[{"href":"https:\/\/www.panalabel.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.panalabel.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.panalabel.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.panalabel.com\/en\/wp-json\/wp\/v2\/comments?post=3731"}],"version-history":[{"count":5,"href":"https:\/\/www.panalabel.com\/en\/wp-json\/wp\/v2\/pages\/3731\/revisions"}],"predecessor-version":[{"id":3746,"href":"https:\/\/www.panalabel.com\/en\/wp-json\/wp\/v2\/pages\/3731\/revisions\/3746"}],"wp:attachment":[{"href":"https:\/\/www.panalabel.com\/en\/wp-json\/wp\/v2\/media?parent=3731"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}